{"id":47,"date":"2024-06-01T05:15:39","date_gmt":"2024-06-01T03:15:39","guid":{"rendered":"https:\/\/talleressantaeulalia.es\/?page_id=47"},"modified":"2025-06-20T00:26:21","modified_gmt":"2025-06-19T22:26:21","slug":"taller-autorizado-tesla","status":"publish","type":"page","link":"https:\/\/talleressantaeulalia.es\/ca\/taller-autorizado-tesla\/","title":{"rendered":"Taller autoritzat Tesla"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"47\" class=\"elementor elementor-47\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-44fa01c e-flex e-con-boxed e-con e-parent\" data-id=\"44fa01c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_blur_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_devices&quot;:[&quot;mobile&quot;],&quot;background_motion_fx_blur_direction&quot;:&quot;out-in&quot;,&quot;background_motion_fx_blur_level&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:7,&quot;sizes&quot;:[]},&quot;background_motion_fx_blur_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:20,&quot;end&quot;:80}}}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-982b6ce e-con-full e-flex e-con e-child\" data-id=\"982b6ce\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-42af833 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"42af833\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounceInLeft&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Reparaci\u00f3n de Carrocer\u00eda y Servicios Asociados <BR>\n\nAprobados por <span style=\"color: #DC0513\">TESLA EN TERRASSA<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c82b52 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"4c82b52\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounceInLeft&quot;,&quot;_animation_delay&quot;:300,&quot;_animation_mobile&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Especialistas en chapa y pintura aprobados por Tesla. En siniestros o golpes, nos encargamos de todo el proceso, coordinando tambi\u00e9n las reparaciones t\u00e9cnicas que tu veh\u00edculo pueda requerir, siempre con tecnolog\u00eda de \u00faltima generaci\u00f3n y bajo supervisi\u00f3n experta.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-06d4ed1 e-flex e-con-boxed e-con e-child\" data-id=\"06d4ed1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c9bc08f e-con-full e-flex e-con e-child\" data-id=\"c9bc08f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8057549 elementor-button-info elementor-align-left elementor-invisible elementor-widget elementor-widget-button\" data-id=\"8057549\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;pulse&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/talleressantaeulalia.es\/ca\/cotizar-online\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">COTIZA ONLINE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-42bbf21 e-con-full e-flex e-con e-child\" data-id=\"42bbf21\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-feb91e7 elementor-button-info elementor-align-left elementor-invisible elementor-widget elementor-widget-button\" data-id=\"feb91e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;pulse&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/talleressantaeulalia.es\/ca\/reservar-cita\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">RESERVA AHORA<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-af6c644 e-con-full e-flex e-con e-child\" data-id=\"af6c644\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ffa829d elementor-invisible elementor-widget elementor-widget-image\" data-id=\"ffa829d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"590\" height=\"167\" src=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/logo-tesla-rojo-imagen-png-body-shop.png\" class=\"attachment-full size-full wp-image-2243\" alt=\"logo tesla rojo imagen png body shop\" srcset=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/logo-tesla-rojo-imagen-png-body-shop.png 590w, https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/logo-tesla-rojo-imagen-png-body-shop-300x85.png 300w\" sizes=\"(max-width: 590px) 100vw, 590px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04a258a elementor-invisible elementor-widget elementor-widget-image\" data-id=\"04a258a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateX_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateX_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:24,&quot;end&quot;:76}},&quot;_animation&quot;:&quot;bounceInRight&quot;,&quot;motion_fx_scale_effect&quot;:&quot;yes&quot;,&quot;motion_fx_scale_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1,&quot;sizes&quot;:[]},&quot;motion_fx_translateX_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;motion_fx_scale_direction&quot;:&quot;out-in&quot;,&quot;motion_fx_scale_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:20,&quot;end&quot;:80}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/tesla-blanco-png-2024-imagen.png\" class=\"attachment-full size-full wp-image-2089\" alt=\"tesla blanco png 2024 imagen\" srcset=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/tesla-blanco-png-2024-imagen.png 1200w, https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/tesla-blanco-png-2024-imagen-300x200.png 300w, https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/tesla-blanco-png-2024-imagen-1024x683.png 1024w, https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/tesla-blanco-png-2024-imagen-768x512.png 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-52423fd e-flex e-con-boxed e-con e-parent\" data-id=\"52423fd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b42b92e e-flex e-con-boxed e-con e-child\" data-id=\"b42b92e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f988cda e-flex e-con-boxed e-con e-child\" data-id=\"f988cda\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-02ca1f9 elementor-invisible elementor-widget elementor-widget-counter\" data-id=\"02ca1f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">REPARACIONES<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\">+<\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"890\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-131255b e-flex e-con-boxed e-con e-child\" data-id=\"131255b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cfb73a9 elementor-invisible elementor-widget elementor-widget-counter\" data-id=\"cfb73a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">CLIENTES SATISFECHOS<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\">+<\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"1432\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a275e9d e-flex e-con-boxed e-con e-parent\" data-id=\"a275e9d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-bb83fab e-flex e-con-boxed e-con e-child\" data-id=\"bb83fab\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ca1ca0c e-flex e-con-boxed e-con e-child\" data-id=\"ca1ca0c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6b3ef8b elementor-invisible elementor-widget elementor-widget-image\" data-id=\"6b3ef8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_scale_effect&quot;:&quot;yes&quot;,&quot;motion_fx_scale_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:6,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;bounceInLeft&quot;,&quot;motion_fx_scale_direction&quot;:&quot;out-in&quot;,&quot;motion_fx_scale_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:20,&quot;end&quot;:80}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"974\" height=\"568\" src=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/tesla-azul-de-talleres.png\" class=\"attachment-full size-full wp-image-3602\" alt=\"tesla azul de talleres\" srcset=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/tesla-azul-de-talleres.png 974w, https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/tesla-azul-de-talleres-300x175.png 300w, https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/tesla-azul-de-talleres-768x448.png 768w\" sizes=\"(max-width: 974px) 100vw, 974px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-87f3cde e-flex e-con-boxed e-con e-child\" data-id=\"87f3cde\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-649629f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"649629f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-885a9b2 elementor-widget elementor-widget-heading\" data-id=\"885a9b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">NUESTRO COMPROMISO<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67a15a0 elementor-widget elementor-widget-heading\" data-id=\"67a15a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">CALIDAD Y TRANQUILIDAD<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c49a58 elementor-widget elementor-widget-heading\" data-id=\"8c49a58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Nos dedicamos a ofrecer el mejor servicio para tu Tesla, garantizando calidad y fiabilidad en cada intervenci\u00f3n. Nuestra pasi\u00f3n por la tecnolog\u00eda y el amor por nuestra profesi\u00f3n nos impulsan a brindar un servicio excepcional.<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-108a25f elementor-widget elementor-widget-image\" data-id=\"108a25f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"181\" height=\"66\" src=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/logo-tesla-approvedbodyshop.png\" class=\"attachment-large size-large wp-image-108\" alt=\"logo tesla approved body shop\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9679e4d e-flex e-con-boxed e-con e-parent\" data-id=\"9679e4d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-46cba1d e-flex e-con-boxed e-con e-child\" data-id=\"46cba1d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4be75b8 elementor-widget elementor-widget-image\" data-id=\"4be75b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"590\" height=\"167\" src=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/logo-tesla-rojo-imagen-png-body-shop.png\" class=\"attachment-large size-large wp-image-2243\" alt=\"logo tesla rojo imagen png body shop\" srcset=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/logo-tesla-rojo-imagen-png-body-shop.png 590w, https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/logo-tesla-rojo-imagen-png-body-shop-300x85.png 300w\" sizes=\"(max-width: 590px) 100vw, 590px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05ec877 elementor-widget elementor-widget-heading\" data-id=\"05ec877\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SERVICIOS ESPECIALIZADOS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eba896f e-flex e-con-boxed e-con e-child\" data-id=\"eba896f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d7414b4 e-flex e-con-boxed e-con e-child\" data-id=\"d7414b4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37adc3e e-transform elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"37adc3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;swing&quot;,&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"168\" height=\"171\" src=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/reparacion-de-accidentes-icon-png.png\" class=\"attachment-full size-full wp-image-1313\" alt=\"reparacion de accidentes icon png\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><hr><\/h3><p class=\"elementor-image-box-description\">REPARACI\u00d3N DE ACCIDENTES<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3aa94e9 e-flex e-con-boxed e-con e-child\" data-id=\"3aa94e9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dd2c54e e-transform elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"dd2c54e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;swing&quot;,&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"190\" height=\"189\" src=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/gestion-de-accidentes-icon-png.png\" class=\"attachment-full size-full wp-image-1314\" alt=\"gestion de accidentes icon png\" srcset=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/gestion-de-accidentes-icon-png.png 190w, https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/gestion-de-accidentes-icon-png-150x150.png 150w\" sizes=\"(max-width: 190px) 100vw, 190px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><hr><\/h3><p class=\"elementor-image-box-description\">GESTI\u00d3N DE ACCIDENTES<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1b2325a e-flex e-con-boxed e-con e-child\" data-id=\"1b2325a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-187b833 e-transform elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"187b833\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;swing&quot;,&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"217\" height=\"157\" src=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/reparacion-de-carrocerias-png-icon.png\" class=\"attachment-full size-full wp-image-1315\" alt=\"reparacion de carrocerias png icon\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><hr><\/h3><p class=\"elementor-image-box-description\">REPARACI\u00d3N DE CARROCERIAS<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f34c09b e-flex e-con-boxed e-con e-child\" data-id=\"f34c09b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ec4dae e-transform elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"2ec4dae\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.2,&quot;sizes&quot;:[]},&quot;_animation&quot;:&quot;swing&quot;,&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"185\" src=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/remplazo-de-parabrisas-tesla-png-imagen-icon.png\" class=\"attachment-full size-full wp-image-1316\" alt=\"remplazo de parabrisas tesla png imagen icon\" srcset=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/remplazo-de-parabrisas-tesla-png-imagen-icon.png 185w, https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/remplazo-de-parabrisas-tesla-png-imagen-icon-150x150.png 150w\" sizes=\"(max-width: 185px) 100vw, 185px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><hr><\/h3><p class=\"elementor-image-box-description\">REEMPLAZO DE PARABRISAS TESLA<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1f4c345 e-flex e-con-boxed e-con e-parent\" data-id=\"1f4c345\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a299183 e-flex e-con-boxed e-con e-child\" data-id=\"a299183\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-da30d3a e-flex e-con-boxed e-con e-child\" data-id=\"da30d3a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b1c6a51 elementor-widget elementor-widget-image\" data-id=\"b1c6a51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"609\" height=\"541\" src=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/tecnologia-de-vanguardia-imagen-talleres-santa-eulalia.png\" class=\"attachment-full size-full wp-image-1330\" alt=\"tecnologia de vanguardia imagen talleres santa eulalia\" srcset=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/tecnologia-de-vanguardia-imagen-talleres-santa-eulalia.png 609w, https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/tecnologia-de-vanguardia-imagen-talleres-santa-eulalia-300x267.png 300w\" sizes=\"(max-width: 609px) 100vw, 609px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ae6d73f e-flex e-con-boxed e-con e-child\" data-id=\"ae6d73f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c3c4e7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2c3c4e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8783a2 elementor-widget elementor-widget-heading\" data-id=\"b8783a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">TECNOLOG\u00cdA DE VANGUARDIA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5efe1d elementor-widget elementor-widget-heading\" data-id=\"c5efe1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Equipos de Diagn\u00f3stico Modernos<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a832658 elementor-widget elementor-widget-heading\" data-id=\"a832658\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Disponemos de las \u00faltimas herramientas de diagnosis, como Bosch, Texa y Autel, para atender todas las necesidades de tu Tesla. Utilizamos tecnolog\u00eda PassThru para intervenciones el\u00e9ctricas avanzadas, incluyendo flasheo de software y reprogramaciones ECU.<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-997f840 e-con-full e-flex e-con e-child\" data-id=\"997f840\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a78d37b e-flex e-con-boxed e-con e-child\" data-id=\"a78d37b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a9c9187 elementor-widget elementor-widget-gallery\" data-id=\"a9c9187\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;image_hover_animation&quot;:&quot;move-contained-left&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;gallery_layout&quot;:&quot;grid&quot;,&quot;columns&quot;:4,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;aspect_ratio&quot;:&quot;3:2&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/tesla-abierto-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a9c9187\" data-elementor-lightbox-title=\"tesla abierto\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzYwOCwidXJsIjoiaHR0cHM6XC9cL3RhbGxlcmVzc2FudGFldWxhbGlhLmVzXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wNlwvdGVzbGEtYWJpZXJ0by1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiYTljOTE4NyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/tesla-abierto-169x300.jpg\" data-width=\"169\" data-height=\"300\" aria-label=\"tesla abierto\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/cambio-y-revision-de-frenos.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a9c9187\" data-elementor-lightbox-title=\"cambio y revision de frenos\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzU4OSwidXJsIjoiaHR0cHM6XC9cL3RhbGxlcmVzc2FudGFldWxhbGlhLmVzXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wNlwvY2FtYmlvLXktcmV2aXNpb24tZGUtZnJlbm9zLnBuZyIsInNsaWRlc2hvdyI6ImE5YzkxODcifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/cambio-y-revision-de-frenos-300x300.png\" data-width=\"300\" data-height=\"300\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/piliendo-tesla-scaled.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a9c9187\" data-elementor-lightbox-title=\"puliendo tesla\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzYwOSwidXJsIjoiaHR0cHM6XC9cL3RhbGxlcmVzc2FudGFldWxhbGlhLmVzXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wNlwvcGlsaWVuZG8tdGVzbGEtc2NhbGVkLmpwZWciLCJzbGlkZXNob3ciOiJhOWM5MTg3In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/piliendo-tesla-225x300.jpeg\" data-width=\"225\" data-height=\"300\" aria-label=\"puliendo tesla\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/escaneando-un-tesla-scaled.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a9c9187\" data-elementor-lightbox-title=\"escaneando un tesla\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzYxMSwidXJsIjoiaHR0cHM6XC9cL3RhbGxlcmVzc2FudGFldWxhbGlhLmVzXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wNlwvZXNjYW5lYW5kby11bi10ZXNsYS1zY2FsZWQuanBlZyIsInNsaWRlc2hvdyI6ImE5YzkxODcifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/escaneando-un-tesla-225x300.jpeg\" data-width=\"225\" data-height=\"300\" aria-label=\"escaneando un tesla\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/raparando-tesla-1-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a9c9187\" data-elementor-lightbox-title=\"raparando tesla 1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzYxMiwidXJsIjoiaHR0cHM6XC9cL3RhbGxlcmVzc2FudGFldWxhbGlhLmVzXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wNlwvcmFwYXJhbmRvLXRlc2xhLTEtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6ImE5YzkxODcifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/raparando-tesla-1-165x300.jpg\" data-width=\"165\" data-height=\"300\" aria-label=\"raparando tesla 1\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/tesla-grande-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a9c9187\" data-elementor-lightbox-title=\"tesla grande\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzYwNywidXJsIjoiaHR0cHM6XC9cL3RhbGxlcmVzc2FudGFldWxhbGlhLmVzXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wNlwvdGVzbGEtZ3JhbmRlLXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiJhOWM5MTg3In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/tesla-grande-225x300.jpg\" data-width=\"225\" data-height=\"300\" aria-label=\"tesla grande\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/reparando-tesla-2-scaled.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"a9c9187\" data-elementor-lightbox-title=\"reparando tesla 2\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MzYxMCwidXJsIjoiaHR0cHM6XC9cL3RhbGxlcmVzc2FudGFldWxhbGlhLmVzXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI0XC8wNlwvcmVwYXJhbmRvLXRlc2xhLTItc2NhbGVkLmpwZWciLCJzbGlkZXNob3ciOiJhOWM5MTg3In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/reparando-tesla-2-225x300.jpeg\" data-width=\"225\" data-height=\"300\" aria-label=\"reparando tesla 2\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4210823 e-flex e-con-boxed e-con e-child\" data-id=\"4210823\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-44dfddb e-flex e-con-boxed e-con e-child\" data-id=\"44dfddb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6583aa6 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"6583aa6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateX_effect&quot;:&quot;yes&quot;,&quot;_animation&quot;:&quot;bounceInRight&quot;,&quot;motion_fx_translateX_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;motion_fx_translateX_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"715\" height=\"286\" src=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/auto-tesla-de-lado-imagen-png.png\" class=\"attachment-full size-full wp-image-1346\" alt=\"auto tesla de lado imagen png\" srcset=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/auto-tesla-de-lado-imagen-png.png 715w, https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/auto-tesla-de-lado-imagen-png-300x120.png 300w\" sizes=\"(max-width: 715px) 100vw, 715px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1f319a9 e-flex e-con-boxed e-con e-parent\" data-id=\"1f319a9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;shape_divider_bottom&quot;:&quot;tilt&quot;,&quot;shape_divider_top&quot;:&quot;tilt&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-13409ac e-flex e-con-boxed e-con e-child\" data-id=\"13409ac\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-765d95c e-flex e-con-boxed e-con e-child\" data-id=\"765d95c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4281718 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4281718\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ad4e58 elementor-widget elementor-widget-heading\" data-id=\"4ad4e58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CERTIFICADO POR TESLA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5ead48 elementor-widget elementor-widget-heading\" data-id=\"d5ead48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Calidad Garantizada<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-980564e e-flex e-con-boxed e-con e-child\" data-id=\"980564e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-95de719 e-flex e-con-boxed e-con e-child\" data-id=\"95de719\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0550407 elementor-widget elementor-widget-heading\" data-id=\"0550407\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Somos un Tesla Approved Body Shop. Realizamos reparaciones de carrocer\u00eda y pintura con est\u00e1ndares de f\u00e1brica, utilizando tecnolog\u00eda de \u00faltima generaci\u00f3n y personal cualificado por Tesla para garantizar calidad y seguridad.<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-476f8b7 elementor-absolute elementor-widget elementor-widget-image\" data-id=\"476f8b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"496\" height=\"494\" src=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/certificado-rojo-icon-png-imagen.png\" class=\"attachment-large size-large wp-image-1349\" alt=\"certificado rojo icon png imagen\" srcset=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/certificado-rojo-icon-png-imagen.png 496w, https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/certificado-rojo-icon-png-imagen-300x300.png 300w, https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/certificado-rojo-icon-png-imagen-150x150.png 150w\" sizes=\"(max-width: 496px) 100vw, 496px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-074732d elementor-widget elementor-widget-image\" data-id=\"074732d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/tesla-rojo-talleres-santa-eulalia.png\" class=\"attachment-full size-full wp-image-2092\" alt=\"tesla rojo talleres santa eulalia\" srcset=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/tesla-rojo-talleres-santa-eulalia.png 1200w, https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/tesla-rojo-talleres-santa-eulalia-300x200.png 300w, https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/tesla-rojo-talleres-santa-eulalia-1024x683.png 1024w, https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/tesla-rojo-talleres-santa-eulalia-768x512.png 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fefdb60 elementor-widget__width-initial elementor-absolute animated-slow elementor-invisible elementor-widget elementor-widget-spacer\" data-id=\"fefdb60\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;flash&quot;}\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4bdcd2d e-flex e-con-boxed e-con e-child\" data-id=\"4bdcd2d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cbe2e6a elementor-widget elementor-widget-image\" data-id=\"cbe2e6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"637\" height=\"480\" src=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/certificado-tesla-de-talleres-santa-eulalia.png\" class=\"attachment-large size-large wp-image-1347\" alt=\"certificado tesla de talleres santa eulalia\" srcset=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/certificado-tesla-de-talleres-santa-eulalia.png 637w, https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/certificado-tesla-de-talleres-santa-eulalia-300x226.png 300w\" sizes=\"(max-width: 637px) 100vw, 637px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-24defdb e-flex e-con-boxed e-con e-parent\" data-id=\"24defdb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-99a3907 e-flex e-con-boxed e-con e-child\" data-id=\"99a3907\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f48fd77 e-flex e-con-boxed e-con e-child\" data-id=\"f48fd77\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b6134f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5b6134f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20e6d88 elementor-widget elementor-widget-heading\" data-id=\"20e6d88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ACCESO A SOFTWARE DE <br>\nDIAGN\u00d3STICO ORIGINAL<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-005f99f elementor-widget elementor-widget-heading\" data-id=\"005f99f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Utilizamos software de diagnosis originales autorizado por la Marca asegurando un diagn\u00f3stico preciso y eficiente para tu Tesla.<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b521d8d elementor-widget elementor-widget-image\" data-id=\"b521d8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"590\" height=\"167\" src=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/logo-tesla-rojo-imagen-png-body-shop.png\" class=\"attachment-full size-full wp-image-2243\" alt=\"logo tesla rojo imagen png body shop\" srcset=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/logo-tesla-rojo-imagen-png-body-shop.png 590w, https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/logo-tesla-rojo-imagen-png-body-shop-300x85.png 300w\" sizes=\"(max-width: 590px) 100vw, 590px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-29406c4 e-flex e-con-boxed e-con e-child\" data-id=\"29406c4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9711fc4 e-flex e-con-boxed e-con e-child\" data-id=\"9711fc4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8bd72fa elementor-absolute elementor-widget elementor-widget-image\" data-id=\"8bd72fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateX_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateX_direction&quot;:&quot;negative&quot;,&quot;motion_fx_translateX_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;motion_fx_translateX_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"516\" height=\"285\" src=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/reserva-carro-tesla-blanco-png.png\" class=\"attachment-full size-full wp-image-2200\" alt=\"reserva carro tesla blanco png\" srcset=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/reserva-carro-tesla-blanco-png.png 516w, https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/reserva-carro-tesla-blanco-png-300x166.png 300w\" sizes=\"(max-width: 516px) 100vw, 516px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4b751b elementor-absolute elementor-widget elementor-widget-image\" data-id=\"c4b751b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateX_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateX_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;motion_fx_translateX_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"544\" height=\"436\" src=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/tesla-presupuesto-de-frente.png\" class=\"attachment-full size-full wp-image-1367\" alt=\"tesla presupuesto de frente\" srcset=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/tesla-presupuesto-de-frente.png 544w, https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/tesla-presupuesto-de-frente-300x240.png 300w\" sizes=\"(max-width: 544px) 100vw, 544px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-85ddc59 e-flex e-con-boxed e-con e-child\" data-id=\"85ddc59\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-790df07 e-flex e-con-boxed e-con e-child\" data-id=\"790df07\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2d7bc9a elementor-widget elementor-widget-heading\" data-id=\"2d7bc9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">RESERVAR<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e8a14d elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"3e8a14d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Como Tesla Approved Body Shop en Terrassa, trabajamos con precisi\u00f3n, cuidado y est\u00e1ndares oficiales para devolv\u00e9rtelo como nuevo.<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1fd336 elementor-absolute elementor-invisible elementor-widget elementor-widget-button\" data-id=\"a1fd336\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounceInUp&quot;,&quot;_animation_delay&quot;:300,&quot;_animation_mobile&quot;:&quot;none&quot;,&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/talleressantaeulalia.es\/ca\/reservar-cita-tesla\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">RESERVAR<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9494661 e-flex e-con-boxed e-con e-child\" data-id=\"9494661\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0695926 elementor-widget elementor-widget-heading\" data-id=\"0695926\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PRESUPUESTAR<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc7740d elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"fc7740d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">\u00bfQuieres saber cuanto cuesta el servicio que necesitas?, llena el formulario y te haremos un presupuesto totalmente online<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2489a9 elementor-align-center elementor-absolute elementor-invisible elementor-widget elementor-widget-button\" data-id=\"b2489a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounceInUp&quot;,&quot;_animation_delay&quot;:300,&quot;_animation_mobile&quot;:&quot;none&quot;,&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/talleressantaeulalia.es\/ca\/cotizar-online-tesla\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">PRESUPUESTO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Reparaci\u00f3n de Carrocer\u00eda y Servicios Asociados Aprobados por TESLA EN TERRASSA Especialistas en chapa y pintura aprobados por Tesla. En siniestros o golpes, nos encargamos de todo el proceso, coordinando tambi\u00e9n las reparaciones t\u00e9cnicas que tu veh\u00edculo pueda requerir, siempre con tecnolog\u00eda de \u00faltima generaci\u00f3n y bajo supervisi\u00f3n experta. COTIZA ONLINE RESERVA AHORA REPARACIONES + [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-47","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reparaci\u00f3n y mantenimiento especializada para Tesla en Terrassa - Talleres Santa Eulalia<\/title>\n<meta name=\"description\" content=\"Un taller certificado por Tesla, reparaci\u00f3n y mantenimiento de veh\u00edculos Tesla en Barcelona Terrassa, calidad garantizada.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/talleressantaeulalia.es\/ca\/taller-autorizado-tesla\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reparaci\u00f3n y mantenimiento especializada para Tesla en Terrassa - Talleres Santa Eulalia\" \/>\n<meta property=\"og:description\" content=\"Un taller certificado por Tesla, reparaci\u00f3n y mantenimiento de veh\u00edculos Tesla en Barcelona Terrassa, calidad garantizada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/talleressantaeulalia.es\/ca\/taller-autorizado-tesla\/\" \/>\n<meta property=\"og:site_name\" content=\"Talleres Santa Eulalia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/talleressantaeulalia\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-19T22:26:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/logo-tesla-rojo-imagen-png-body-shop.png\" \/>\n\t<meta property=\"og:image:width\" content=\"590\" \/>\n\t<meta property=\"og:image:height\" content=\"167\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/talleressantaeulalia.es\\\/taller-autorizado-tesla\\\/\",\"url\":\"https:\\\/\\\/talleressantaeulalia.es\\\/taller-autorizado-tesla\\\/\",\"name\":\"Reparaci\u00f3n y mantenimiento especializada para Tesla en Terrassa - Talleres Santa Eulalia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/talleressantaeulalia.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/talleressantaeulalia.es\\\/taller-autorizado-tesla\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/talleressantaeulalia.es\\\/taller-autorizado-tesla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/talleressantaeulalia.es\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/logo-tesla-rojo-imagen-png-body-shop.png\",\"datePublished\":\"2024-06-01T03:15:39+00:00\",\"dateModified\":\"2025-06-19T22:26:21+00:00\",\"description\":\"Un taller certificado por Tesla, reparaci\u00f3n y mantenimiento de veh\u00edculos Tesla en Barcelona Terrassa, calidad garantizada.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/talleressantaeulalia.es\\\/taller-autorizado-tesla\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/talleressantaeulalia.es\\\/taller-autorizado-tesla\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/talleressantaeulalia.es\\\/taller-autorizado-tesla\\\/#primaryimage\",\"url\":\"https:\\\/\\\/talleressantaeulalia.es\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/logo-tesla-rojo-imagen-png-body-shop.png\",\"contentUrl\":\"https:\\\/\\\/talleressantaeulalia.es\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/logo-tesla-rojo-imagen-png-body-shop.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/talleressantaeulalia.es\\\/taller-autorizado-tesla\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/talleressantaeulalia.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Taller autorizado Tesla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/talleressantaeulalia.es\\\/#website\",\"url\":\"https:\\\/\\\/talleressantaeulalia.es\\\/\",\"name\":\"Talleres Santa Eulalia\",\"description\":\"Taller mecanio en Terrassa, reparaci\u00f3n de veh\u00edculos, servicio oficial Tesla. Ofrecemos servicios de mec\u00e1nica, chapa y pintura con la garant\u00eda de calidad desde 1978\",\"publisher\":{\"@id\":\"https:\\\/\\\/talleressantaeulalia.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/talleressantaeulalia.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/talleressantaeulalia.es\\\/#organization\",\"name\":\"Talleres Santa Eulalia\",\"url\":\"https:\\\/\\\/talleressantaeulalia.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/talleressantaeulalia.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/talleressantaeulalia.es\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Logo-Talleres-Santa-Eulalia.png\",\"contentUrl\":\"https:\\\/\\\/talleressantaeulalia.es\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Logo-Talleres-Santa-Eulalia.png\",\"width\":253,\"height\":75,\"caption\":\"Talleres Santa Eulalia\"},\"image\":{\"@id\":\"https:\\\/\\\/talleressantaeulalia.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/talleressantaeulalia\",\"https:\\\/\\\/www.instagram.com\\\/talleres_santa_eulalia?igshid=q7vow4s39hla\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCs2QRdoHYKCNgHkm6bKUVmg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reparaci\u00f3 i manteniment especialitzada per Tesla a Terrassa - Tallers Santa Eulalia","description":"Un taller certificat per Tesla, reparaci\u00f3 i manteniment de vehicles Tesla a Barcelona Terrassa, qualitat garantida.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/talleressantaeulalia.es\/ca\/taller-autorizado-tesla\/","og_locale":"ca_ES","og_type":"article","og_title":"Reparaci\u00f3n y mantenimiento especializada para Tesla en Terrassa - Talleres Santa Eulalia","og_description":"Un taller certificado por Tesla, reparaci\u00f3n y mantenimiento de veh\u00edculos Tesla en Barcelona Terrassa, calidad garantizada.","og_url":"https:\/\/talleressantaeulalia.es\/ca\/taller-autorizado-tesla\/","og_site_name":"Talleres Santa Eulalia","article_publisher":"https:\/\/www.facebook.com\/talleressantaeulalia","article_modified_time":"2025-06-19T22:26:21+00:00","og_image":[{"width":590,"height":167,"url":"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/logo-tesla-rojo-imagen-png-body-shop.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"5 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/talleressantaeulalia.es\/taller-autorizado-tesla\/","url":"https:\/\/talleressantaeulalia.es\/taller-autorizado-tesla\/","name":"Reparaci\u00f3 i manteniment especialitzada per Tesla a Terrassa - Tallers Santa Eulalia","isPartOf":{"@id":"https:\/\/talleressantaeulalia.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/talleressantaeulalia.es\/taller-autorizado-tesla\/#primaryimage"},"image":{"@id":"https:\/\/talleressantaeulalia.es\/taller-autorizado-tesla\/#primaryimage"},"thumbnailUrl":"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/logo-tesla-rojo-imagen-png-body-shop.png","datePublished":"2024-06-01T03:15:39+00:00","dateModified":"2025-06-19T22:26:21+00:00","description":"Un taller certificat per Tesla, reparaci\u00f3 i manteniment de vehicles Tesla a Barcelona Terrassa, qualitat garantida.","breadcrumb":{"@id":"https:\/\/talleressantaeulalia.es\/taller-autorizado-tesla\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/talleressantaeulalia.es\/taller-autorizado-tesla\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/talleressantaeulalia.es\/taller-autorizado-tesla\/#primaryimage","url":"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/logo-tesla-rojo-imagen-png-body-shop.png","contentUrl":"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/logo-tesla-rojo-imagen-png-body-shop.png"},{"@type":"BreadcrumbList","@id":"https:\/\/talleressantaeulalia.es\/taller-autorizado-tesla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/talleressantaeulalia.es\/"},{"@type":"ListItem","position":2,"name":"Taller autorizado Tesla"}]},{"@type":"WebSite","@id":"https:\/\/talleressantaeulalia.es\/#website","url":"https:\/\/talleressantaeulalia.es\/","name":"Tallers Santa Eul\u00e0lia","description":"Taller mecani a Terrassa, reparaci\u00f3 de vehicles, servei oficial Tesla. Oferim serveis de mec\u00e0nica, xapa i pintura amb la garantia de qualitat des del 1978","publisher":{"@id":"https:\/\/talleressantaeulalia.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/talleressantaeulalia.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/talleressantaeulalia.es\/#organization","name":"Tallers Santa Eul\u00e0lia","url":"https:\/\/talleressantaeulalia.es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/talleressantaeulalia.es\/#\/schema\/logo\/image\/","url":"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/Logo-Talleres-Santa-Eulalia.png","contentUrl":"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/Logo-Talleres-Santa-Eulalia.png","width":253,"height":75,"caption":"Talleres Santa Eulalia"},"image":{"@id":"https:\/\/talleressantaeulalia.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/talleressantaeulalia","https:\/\/www.instagram.com\/talleres_santa_eulalia?igshid=q7vow4s39hla","https:\/\/www.youtube.com\/channel\/UCs2QRdoHYKCNgHkm6bKUVmg"]}]}},"_links":{"self":[{"href":"https:\/\/talleressantaeulalia.es\/ca\/wp-json\/wp\/v2\/pages\/47","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/talleressantaeulalia.es\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/talleressantaeulalia.es\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/talleressantaeulalia.es\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/talleressantaeulalia.es\/ca\/wp-json\/wp\/v2\/comments?post=47"}],"version-history":[{"count":195,"href":"https:\/\/talleressantaeulalia.es\/ca\/wp-json\/wp\/v2\/pages\/47\/revisions"}],"predecessor-version":[{"id":5742,"href":"https:\/\/talleressantaeulalia.es\/ca\/wp-json\/wp\/v2\/pages\/47\/revisions\/5742"}],"wp:attachment":[{"href":"https:\/\/talleressantaeulalia.es\/ca\/wp-json\/wp\/v2\/media?parent=47"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}