{"id":8,"count":4,"description":"","link":"https:\/\/talleressantaeulalia.es\/ca\/category\/proyectos\/","name":"Projectes","slug":"proyectos","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Proyectos archivos - Talleres Santa Eulalia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/talleressantaeulalia.es\/ca\/category\/proyectos\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Proyectos archivos - Talleres Santa Eulalia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/talleressantaeulalia.es\/ca\/category\/proyectos\/\" \/>\n<meta property=\"og:site_name\" content=\"Talleres Santa Eulalia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/talleressantaeulalia.es\\\/category\\\/proyectos\\\/\",\"url\":\"https:\\\/\\\/talleressantaeulalia.es\\\/category\\\/proyectos\\\/\",\"name\":\"Proyectos archivos - Talleres Santa Eulalia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/talleressantaeulalia.es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/talleressantaeulalia.es\\\/category\\\/proyectos\\\/#breadcrumb\"},\"inLanguage\":\"ca\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/talleressantaeulalia.es\\\/category\\\/proyectos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/talleressantaeulalia.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyectos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/talleressantaeulalia.es\\\/#website\",\"url\":\"https:\\\/\\\/talleressantaeulalia.es\\\/\",\"name\":\"Talleres Santa Eulalia\",\"description\":\"Taller mecanio en Terrassa, reparaci\u00f3n de veh\u00edculos, servicio oficial Tesla. Ofrecemos servicios de mec\u00e1nica, chapa y pintura con la garant\u00eda de calidad desde 1978\",\"publisher\":{\"@id\":\"https:\\\/\\\/talleressantaeulalia.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/talleressantaeulalia.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/talleressantaeulalia.es\\\/#organization\",\"name\":\"Talleres Santa Eulalia\",\"url\":\"https:\\\/\\\/talleressantaeulalia.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/talleressantaeulalia.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/talleressantaeulalia.es\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Logo-Talleres-Santa-Eulalia.png\",\"contentUrl\":\"https:\\\/\\\/talleressantaeulalia.es\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Logo-Talleres-Santa-Eulalia.png\",\"width\":253,\"height\":75,\"caption\":\"Talleres Santa Eulalia\"},\"image\":{\"@id\":\"https:\\\/\\\/talleressantaeulalia.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/talleressantaeulalia\",\"https:\\\/\\\/www.instagram.com\\\/talleres_santa_eulalia?igshid=q7vow4s39hla\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCs2QRdoHYKCNgHkm6bKUVmg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proyectos archivos - Talleres Santa Eulalia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/talleressantaeulalia.es\/ca\/category\/proyectos\/","og_locale":"ca_ES","og_type":"article","og_title":"Proyectos archivos - Talleres Santa Eulalia","og_url":"https:\/\/talleressantaeulalia.es\/ca\/category\/proyectos\/","og_site_name":"Talleres Santa Eulalia","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/talleressantaeulalia.es\/category\/proyectos\/","url":"https:\/\/talleressantaeulalia.es\/category\/proyectos\/","name":"Proyectos archivos - Talleres Santa Eulalia","isPartOf":{"@id":"https:\/\/talleressantaeulalia.es\/#website"},"breadcrumb":{"@id":"https:\/\/talleressantaeulalia.es\/category\/proyectos\/#breadcrumb"},"inLanguage":"ca"},{"@type":"BreadcrumbList","@id":"https:\/\/talleressantaeulalia.es\/category\/proyectos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/talleressantaeulalia.es\/"},{"@type":"ListItem","position":2,"name":"Proyectos"}]},{"@type":"WebSite","@id":"https:\/\/talleressantaeulalia.es\/#website","url":"https:\/\/talleressantaeulalia.es\/","name":"Tallers Santa Eul\u00e0lia","description":"Taller mecani a Terrassa, reparaci\u00f3 de vehicles, servei oficial Tesla. Oferim serveis de mec\u00e0nica, xapa i pintura amb la garantia de qualitat des del 1978","publisher":{"@id":"https:\/\/talleressantaeulalia.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/talleressantaeulalia.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/talleressantaeulalia.es\/#organization","name":"Tallers Santa Eul\u00e0lia","url":"https:\/\/talleressantaeulalia.es\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/talleressantaeulalia.es\/#\/schema\/logo\/image\/","url":"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/Logo-Talleres-Santa-Eulalia.png","contentUrl":"https:\/\/talleressantaeulalia.es\/wp-content\/uploads\/2024\/06\/Logo-Talleres-Santa-Eulalia.png","width":253,"height":75,"caption":"Talleres Santa Eulalia"},"image":{"@id":"https:\/\/talleressantaeulalia.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/talleressantaeulalia","https:\/\/www.instagram.com\/talleres_santa_eulalia?igshid=q7vow4s39hla","https:\/\/www.youtube.com\/channel\/UCs2QRdoHYKCNgHkm6bKUVmg"]}]}},"_links":{"self":[{"href":"https:\/\/talleressantaeulalia.es\/ca\/wp-json\/wp\/v2\/categories\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/talleressantaeulalia.es\/ca\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/talleressantaeulalia.es\/ca\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/talleressantaeulalia.es\/ca\/wp-json\/wp\/v2\/posts?categories=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}